{"id":31246,"date":"2024-09-18T09:56:44","date_gmt":"2024-09-18T07:56:44","guid":{"rendered":"https:\/\/roxxlight.com\/cluster-linea-array-backbone-2-2\/"},"modified":"2024-09-18T11:10:38","modified_gmt":"2024-09-18T09:10:38","slug":"cluster-linea-array-backbone-2-2","status":"publish","type":"page","link":"https:\/\/roxxlight.com\/it\/cluster-linea-array-backbone-2-2\/","title":{"rendered":"Cluster-Linea Array-Backbone-2-2"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;2_5,3_5&#8243; _builder_version=&#8221;4.16&#8243; custom_margin=&#8221;-50px||||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.16&#8243; background_color=&#8221;rgba(0,0,0,0)&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/roxxlight.com\/wp-content\/uploads\/2024\/09\/Line-Array-backbone-b2-01.png&#8221; title_text=&#8221;Matrice di linee-backbone-b2-01&#8243; _builder_version=&#8221;4.27.0&#8243; width=&#8221;80%&#8221; animation_style=&#8221;fade&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.0&#8243; text_font=&#8221;|800|||||||&#8221; text_font_size=&#8221;18px&#8221; header_font=&#8221;|300|||||||&#8221; header_text_color=&#8221;#575756&#8243; header_font_size=&#8221;22px&#8221; header_2_font=&#8221;|800|||||||&#8221; header_2_text_color=&#8221;#575756&#8243; header_2_font_size=&#8221;18px&#8221; header_font_size_tablet=&#8221;&#8221; header_font_size_phone=&#8221;20px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1><strong>CLUSTER Line Array <\/strong>| Backbone 2+2<\/h1>\n<p>[\/et_pb_text][et_pb_text content_tablet=&#8221;<\/p>\n<p>Il CLUSTER Line Array Set comprende una staffa per il lato sinistro e una per il lato destro, progettate per essere universalmente compatibili con il sistema CLUSTER, sia che tu stia lavorando con il B4, il B2 o l&apos;S2.<br \/>\nQueste staffe garantiscono un collegamento sicuro e affidabile per qualsiasi combinazione di apparecchi. <\/p>\n<p>&#8221; content_phone=&#8221;<\/p>\n<p>Il backbone 2+2 collega due 2-Lite, sia che si utilizzi B2+B2, S2+S2 o uno di questi.<br \/>\nOgni backbone del CLUSTER Line Array Set offre un&apos;ampia gamma di regolazioni angolari, tra cui angoli positivi da 0\u00b0 a 20\u00b0 e angoli negativi da -2,5\u00b0 a -20\u00b0. <\/p>\n<p>&#8221; content_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.27.0&#8243; text_font=&#8221;||||||||&#8221; text_font_size=&#8221;18px&#8221; header_font=&#8221;|800|||||||&#8221; header_text_color=&#8221;#575756&#8243; header_font_size=&#8221;60px&#8221; header_2_font=&#8221;|700|||||||&#8221; header_2_text_color=&#8221;#575756&#8243; header_2_font_size=&#8221;33px&#8221; header_2_letter_spacing=&#8221;3px&#8221; text_font_size_tablet=&#8221;&#8221; text_font_size_phone=&#8221;16px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Il backbone 2+2 collega due 2-Lite, sia che si utilizzi B2+B2, S2+S2 o uno di questi.<br \/>\nOgni backbone del CLUSTER Line Array Set offre un&#8217;ampia gamma di regolazioni angolari, tra cui angoli positivi da 0\u00b0 a 20\u00b0 e angoli negativi da -2,5\u00b0 a -20\u00b0. <\/p>\n<p>[\/et_pb_text][et_pb_text content_tablet=&#8221;<\/p>\n<p><strong>Caratteristiche principali<\/strong><\/p>\n<ul>\n<li>elemento centrale di supporto del sistema<\/li>\n<li>Il Backbone 2+2 collega due 2-Lite, sia che tu stia usando B2+B2, S2+S2 o uno di ogni apparecchio.<\/li>\n<\/ul>\n<p>&#8221; content_phone=&#8221;<\/p>\n<p><strong>Caratteristiche principali<\/strong><\/p>\n<ul>\n<li>elemento centrale di supporto del sistema<\/li>\n<li>Il Backbone 2+2 collega due 2-Lite, sia che tu stia usando B2+B2, S2+S2 o uno di ogni apparecchio.<\/li>\n<li>Tutti gli angoli positivi: 0 | 1 | 2 | 3 | 4 | 5 | 7,5 | 10 | 12,5 | 15 | 17,5 | 20<\/li>\n<li>Tutti gli angoli negativi: -2.5 | -5 | -7.5 | -10 | -12.5 | -15 | -17.5 | -20<\/li>\n<\/ul>\n<p>&#8221; content_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.27.0&#8243; text_font=&#8221;||||||||&#8221; text_font_size=&#8221;18px&#8221; header_font=&#8221;|800|||||||&#8221; header_text_color=&#8221;#575756&#8243; header_font_size=&#8221;60px&#8221; header_2_font=&#8221;|700|||||||&#8221; header_2_text_color=&#8221;#575756&#8243; header_2_font_size=&#8221;33px&#8221; header_2_letter_spacing=&#8221;3px&#8221; hover_enabled=&#8221;0&#8243; text_font_size_tablet=&#8221;&#8221; text_font_size_phone=&#8221;16px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p><strong>Caratteristiche principali<\/strong><\/p>\n<ul>\n<li>elemento centrale di supporto del sistema<\/li>\n<li>Il Backbone 2+2 collega due 2-Lite, sia che tu stia usando B2+B2, S2+S2 o uno di ogni apparecchio.<\/li>\n<li>Tutti gli angoli positivi: 0 | 1 | 2 | 3 | 4 | 5 | 7,5 | 10 | 12,5 | 15 | 17,5 | 20<\/li>\n<li>Tutti gli angoli negativi: -2.5 | -5 | -7.5 | -10 | -12.5 | -15 | -17.5 | -20<\/li>\n<\/ul>\n<p>[\/et_pb_text][et_pb_tabs active_tab_background_color=&#8221;#dba000&#8243; active_tab_text_color=&#8221;#ffffff&#8221; _builder_version=&#8221;4.27.0&#8243; tab_text_color=&#8221;#575756&#8243; width=&#8221;100%&#8221; module_alignment=&#8221;left&#8221; hover_enabled=&#8221;0&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][et_pb_tab title=&#8221;Dati tecnici&#8221; content_tablet=&#8221;<\/p>\n<h5>Dimensioni e peso<\/h5>\n<ul>\n<li>Materiale: metallo<\/li>\n<li>Dimensioni nette: 570 x 290 x 260 mm (l x h x p)<\/li>\n<li>Dimensioni nette in pollici: 22,44 x 11,42 x 10,24 pollici (l x h x p)<\/li>\n<li>Peso netto: 6,9 kg (15,21 libbre)<\/li>\n<\/ul>\n<p>&#8221; content_phone=&#8221;<\/p>\n<h5>Dimensioni e peso<\/h5>\n<ul>\n<li>Materiale: metallo<\/li>\n<li>Dimensioni nette: 450 x 290 x 230 mm (l x h x p)<\/li>\n<li>Dimensioni nette in pollici: 17,72 x 11,42 x 9,05 pollici (l x h x p)<\/li>\n<li>Peso netto: 3,7 kg (8,15 libbre)<\/li>\n<\/ul>\n<h5>Numero d&apos;ordine<\/h5>\n<ul>\n<li>13909801<\/li>\n<\/ul>\n<p>&#8221; content_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.27.0&#8243; body_line_height=&#8221;1.8em&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h5>Dimensioni e peso<\/h5>\n<ul>\n<li>Materiale: metallo<\/li>\n<li>Dimensioni nette: 450 x 290 x 230 mm (l x h x p)<\/li>\n<li>Dimensioni nette in pollici: 17,72 x 11,42 x 9,05 pollici (l x h x p)<\/li>\n<li>Peso netto: 3,7 kg (8,15 libbre)<\/li>\n<\/ul>\n<h5>Numero d&#8217;ordine<\/h5>\n<ul>\n<li>13909801<\/li>\n<\/ul>\n<p>[\/et_pb_tab][et_pb_tab title=&#8221;Media&#8221; _builder_version=&#8221;4.17.6&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><a href=\"https:\/\/roxxlight.com\/wp-content\/uploads\/2022\/03\/ROXX-Blinder-Rigging-Bracket.jpg\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5028 alignnone size-full\" src=\"https:\/\/roxxlight.com\/wp-content\/uploads\/2021\/02\/Icons-download.png\" alt=\"\" width=\"146\" height=\"146\" srcset=\"https:\/\/roxxlight.com\/wp-content\/uploads\/2021\/02\/Icons-download.png 195w, https:\/\/roxxlight.com\/wp-content\/uploads\/2021\/02\/Icons-download-150x150.png 150w\" sizes=\"(max-width: 146px) 100vw, 146px\" \/><br \/><\/a><\/p>\n<p class=\"p1\">Scarica le immagini dei prodotti qui!<\/p>\n<p>[\/et_pb_tab][\/et_pb_tabs][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.16&#8243; custom_margin=&#8221;-27px||||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_divider divider_style=&#8221;dotted&#8221; divider_position=&#8221;center&#8221; divider_weight=&#8221;2px&#8221; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;-67px||||false|false&#8221; global_module=&#8221;31137&#8243; saved_tabs=&#8221;all&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_6,1_6,1_6,1_6,1_6,1_6&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;2&#8243; disabled_on=&#8221;on|off|off&#8221; _builder_version=&#8221;4.24.0&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;-36px||||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_6&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Array di linee CLUSTER&#8221; url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjMxMTE0In19@&#8221; image=&#8221;https:\/\/roxxlight.com\/wp-content\/uploads\/2024\/09\/Line-Array-side-brackets-01.png&#8221; image_icon_width=&#8221;70%&#8221; content_last_edited=&#8221;off|desktop&#8221; _builder_version=&#8221;4.27.0&#8243; _dynamic_attributes=&#8221;url,link_option_url&#8221; header_level=&#8221;h3&#8243; header_font=&#8221;|300|||||||&#8221; header_text_color=&#8221;#DBA000&#8243; header_font_size=&#8221;14px&#8221; body_line_height=&#8221;1.2em&#8221; text_orientation=&#8221;center&#8221; link_option_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjMxMTE0In19@&#8221; border_color_all=&#8221;#575756&#8243; border_style_all=&#8221;dotted&#8221; border_width_top=&#8221;1px&#8221; border_color_top=&#8221;#575756&#8243; border_width_right=&#8221;1px&#8221; border_width_bottom=&#8221;1px&#8221; border_width_left=&#8221;1px&#8221; image_max_width=&#8221;73%&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: center;\"><strong>Staffe laterali<br \/><\/strong><\/p>\n<p style=\"text-align: center;\">[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_6&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Array di linee CLUSTER&#8221; url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjMxMTQyIn19@&#8221; image=&#8221;https:\/\/roxxlight.com\/wp-content\/uploads\/2024\/09\/Line-Array-backbone-b4-01.png&#8221; image_icon_width=&#8221;70%&#8221; content_tablet=&#8221;<\/p>\n<p style=%22text-align: center;%22><strong>Backbone B4\/S2<\/strong><strong><\/strong><\/p>\n<p style=%22text-align: center;%22><strong><\/strong><\/p>\n<p>&#8221; content_phone=&#8221;<\/p>\n<p style=%22text-align: center;%22><strong>Backbone B4\/S2<\/strong><strong><\/strong><\/p>\n<p style=%22text-align: center;%22><strong><\/strong><\/p>\n<p>&#8221; content_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.27.0&#8243; _dynamic_attributes=&#8221;url,link_option_url&#8221; header_level=&#8221;h3&#8243; header_font=&#8221;|300|||||||&#8221; header_text_color=&#8221;#DBA000&#8243; header_font_size=&#8221;14px&#8221; body_line_height=&#8221;1.2em&#8221; text_orientation=&#8221;center&#8221; link_option_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjMxMTQyIn19@&#8221; border_color_all=&#8221;#575756&#8243; border_style_all=&#8221;dotted&#8221; border_width_top=&#8221;1px&#8221; border_color_top=&#8221;#575756&#8243; border_width_right=&#8221;1px&#8221; border_width_bottom=&#8221;1px&#8221; border_width_left=&#8221;1px&#8221; image_max_width=&#8221;73%&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: center;\"><strong>Backbone 4<\/strong><strong><\/strong><\/p>\n<p style=\"text-align: center;\"><strong><\/strong><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_6&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Array di linee CLUSTER&#8221; url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjMxMTUzIn19@&#8221; image=&#8221;https:\/\/roxxlight.com\/wp-content\/uploads\/2024\/09\/Line-Array-backbone-b2-01.png&#8221; image_icon_width=&#8221;70%&#8221; content_last_edited=&#8221;off|desktop&#8221; _builder_version=&#8221;4.27.0&#8243; _dynamic_attributes=&#8221;url,link_option_url&#8221; header_level=&#8221;h3&#8243; header_font=&#8221;|300|||||||&#8221; header_text_color=&#8221;#DBA000&#8243; header_font_size=&#8221;14px&#8221; body_line_height=&#8221;1.2em&#8221; text_orientation=&#8221;center&#8221; link_option_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjMxMTUzIn19@&#8221; border_color_all=&#8221;#575756&#8243; border_style_all=&#8221;dotted&#8221; border_width_top=&#8221;1px&#8221; border_color_top=&#8221;#575756&#8243; border_width_right=&#8221;1px&#8221; border_width_bottom=&#8221;1px&#8221; border_width_left=&#8221;1px&#8221; image_max_width=&#8221;73%&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: center;\"><strong>Backbone 2+2<\/strong><strong><\/strong><strong><\/strong><\/p>\n<p style=\"text-align: center;\">[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_6&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Array di linee CLUSTER&#8221; url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjMxMTY3In19@&#8221; image=&#8221;https:\/\/roxxlight.com\/wp-content\/uploads\/2024\/09\/Line-Array-flybar-accessory-01.png&#8221; image_icon_width=&#8221;70%&#8221; content_last_edited=&#8221;off|desktop&#8221; _builder_version=&#8221;4.27.0&#8243; _dynamic_attributes=&#8221;url,link_option_url&#8221; header_level=&#8221;h3&#8243; header_font=&#8221;|300|||||||&#8221; header_text_color=&#8221;#DBA000&#8243; header_font_size=&#8221;14px&#8221; body_line_height=&#8221;1.2em&#8221; text_orientation=&#8221;center&#8221; link_option_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjMxMTY3In19@&#8221; border_color_all=&#8221;#575756&#8243; border_style_all=&#8221;dotted&#8221; border_width_top=&#8221;1px&#8221; border_color_top=&#8221;#575756&#8243; border_width_right=&#8221;1px&#8221; border_width_bottom=&#8221;1px&#8221; border_width_left=&#8221;1px&#8221; image_max_width=&#8221;73%&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: center;\"><strong>Fly Bar<br \/><\/strong><\/p>\n<p style=\"text-align: center;\">[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_6&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Array di linee CLUSTER&#8221; url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjMxMTg0In19@&#8221; image=&#8221;https:\/\/roxxlight.com\/wp-content\/uploads\/2024\/09\/Line-Array-floor-bracket-accessories.png&#8221; image_icon_width=&#8221;70%&#8221; content_last_edited=&#8221;off|desktop&#8221; _builder_version=&#8221;4.27.0&#8243; _dynamic_attributes=&#8221;url,link_option_url&#8221; header_level=&#8221;h3&#8243; header_font=&#8221;|300|||||||&#8221; header_text_color=&#8221;#DBA000&#8243; header_font_size=&#8221;14px&#8221; body_line_height=&#8221;1.2em&#8221; text_orientation=&#8221;center&#8221; link_option_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjMxMTg0In19@&#8221; border_color_all=&#8221;#575756&#8243; border_style_all=&#8221;dotted&#8221; border_width_top=&#8221;1px&#8221; border_color_top=&#8221;#575756&#8243; border_width_right=&#8221;1px&#8221; border_width_bottom=&#8221;1px&#8221; border_width_left=&#8221;1px&#8221; image_max_width=&#8221;73%&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: center;\"><strong>Supporto da pavimento<br \/><\/strong><\/p>\n<p style=\"text-align: center;\">[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_6&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row disabled_on=&#8221;off|on|on&#8221; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][dica_divi_carousel multislide=&#8221;on&#8221; centermode=&#8221;on&#8221; dot_nav=&#8221;on&#8221; equal_height=&#8221;on&#8221; advanced_effect=&#8221;1&#8243; dots_color=&#8221;#DBA000&#8243; dots_active_color=&#8221;#575756&#8243; title_background=&#8221;RGBA(255,255,255,0)&#8221; image_sizing=&#8221;80%&#8221; arrow_alignment=&#8221;center&#8221; arrow_font_size=&#8221;35px&#8221; arrow_position_tablet=&#8221;&#8221; arrow_position_phone=&#8221;middle-outside&#8221; arrow_position_last_edited=&#8221;on|phone&#8221; disabled_on=&#8221;off|on|on&#8221; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; title_font=&#8221;|300|||||||&#8221; title_text_align=&#8221;left&#8221; title_text_color=&#8221;#DBA000&#8243; subtitle_font=&#8221;||||||||&#8221; subtitle_text_align=&#8221;center&#8221; subtitle_text_color=&#8221;#575756&#8243; title_text_align_tablet=&#8221;&#8221; title_text_align_phone=&#8221;center&#8221; title_text_align_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][dica_divi_carouselitem title=&#8221;Array di linee CLUSTER&#8221; sub_title=&#8221;Staffe laterali&#8221; button_url_new_window=&#8221;1&#8243; image=&#8221;https:\/\/roxxlight.com\/wp-content\/uploads\/2024\/09\/Line-Array-side-brackets-01.png&#8221; _builder_version=&#8221;4.27.0&#8243; _dynamic_attributes=&#8221;link_option_url&#8221; _module_preset=&#8221;default&#8221; header_text_align=&#8221;center&#8221; link_option_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjMxMTE0In19@&#8221; global_colors_info=&#8221;{}&#8221;][\/dica_divi_carouselitem][dica_divi_carouselitem title=&#8221;Array di linee CLUSTER&#8221; sub_title=&#8221;Backbone 4&#8243; button_url_new_window=&#8221;1&#8243; image=&#8221;https:\/\/roxxlight.com\/wp-content\/uploads\/2024\/09\/Line-Array-backbone-b4-01.png&#8221; _builder_version=&#8221;4.27.0&#8243; _dynamic_attributes=&#8221;link_option_url&#8221; _module_preset=&#8221;default&#8221; header_text_align=&#8221;center&#8221; link_option_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjMxMTQyIn19@&#8221; global_colors_info=&#8221;{}&#8221;][\/dica_divi_carouselitem][dica_divi_carouselitem title=&#8221;Array di linee CLUSTER&#8221; sub_title=&#8221;Backbone 2+2&#8243; button_url_new_window=&#8221;1&#8243; image=&#8221;https:\/\/roxxlight.com\/wp-content\/uploads\/2024\/09\/Line-Array-backbone-b2-01.png&#8221; _builder_version=&#8221;4.27.0&#8243; _dynamic_attributes=&#8221;link_option_url&#8221; _module_preset=&#8221;default&#8221; header_text_align=&#8221;center&#8221; subtitle_font=&#8221;||||||||&#8221; subtitle_text_align=&#8221;center&#8221; subtitle_text_color=&#8221;#575756&#8243; link_option_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjMxMTUzIn19@&#8221; global_colors_info=&#8221;{}&#8221;][\/dica_divi_carouselitem][dica_divi_carouselitem title=&#8221;Array di linee CLUSTER&#8221; sub_title=&#8221;Fly Bar&#8221; button_url_new_window=&#8221;1&#8243; image=&#8221;https:\/\/roxxlight.com\/wp-content\/uploads\/2024\/09\/Line-Array-flybar-accessory-01.png&#8221; _builder_version=&#8221;4.27.0&#8243; _dynamic_attributes=&#8221;link_option_url&#8221; _module_preset=&#8221;default&#8221; header_text_align=&#8221;center&#8221; subtitle_font=&#8221;||||||||&#8221; subtitle_text_align=&#8221;center&#8221; subtitle_text_color=&#8221;#575756&#8243; link_option_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjMxMTY3In19@&#8221; global_colors_info=&#8221;{}&#8221;][\/dica_divi_carouselitem][dica_divi_carouselitem title=&#8221;Array di linee CLUSTER&#8221; sub_title=&#8221;Supporto da pavimento&#8221; button_url_new_window=&#8221;1&#8243; image=&#8221;https:\/\/roxxlight.com\/wp-content\/uploads\/2024\/09\/Line-Array-floor-bracket-accessories.png&#8221; _builder_version=&#8221;4.27.0&#8243; _dynamic_attributes=&#8221;link_option_url&#8221; _module_preset=&#8221;default&#8221; header_text_align=&#8221;center&#8221; link_option_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjMxMTg0In19@&#8221; global_colors_info=&#8221;{}&#8221;][\/dica_divi_carouselitem][\/dica_divi_carousel][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.0&#8243; custom_margin=&#8221;||||false|false&#8221; custom_margin_tablet=&#8221;-100px||-77px||false|false&#8221; custom_margin_phone=&#8221;||||false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_divider divider_style=&#8221;dotted&#8221; divider_position=&#8221;center&#8221; divider_weight=&#8221;2px&#8221; _builder_version=&#8221;4.21.0&#8243; module_alignment=&#8221;center&#8221; custom_margin=&#8221;-24px||-21px||false|false&#8221; custom_margin_tablet=&#8221;-24px||-21px||false|false&#8221; custom_margin_phone=&#8221;11px||-21px||false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_6,1_6,1_6,1_6,1_6,1_6&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;2&#8243; disabled_on=&#8221;on|off|off&#8221; _builder_version=&#8221;4.24.0&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;-36px||||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_6&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;CLUSTER B2 W&#8221; url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjE1MzM4In19@&#8221; image=&#8221;https:\/\/roxxlight.com\/wp-content\/uploads\/2022\/03\/Cluster-B2W-800&#215;800-1.jpg&#8221; image_icon_width=&#8221;70%&#8221; content_last_edited=&#8221;off|desktop&#8221; _builder_version=&#8221;4.24.0&#8243; _dynamic_attributes=&#8221;url,link_option_url&#8221; header_level=&#8221;h3&#8243; header_font=&#8221;|300|||||||&#8221; header_text_color=&#8221;#DBA000&#8243; header_font_size=&#8221;14px&#8221; body_line_height=&#8221;1.2em&#8221; text_orientation=&#8221;center&#8221; link_option_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjE1MzM4In19@&#8221; border_color_all=&#8221;#575756&#8243; border_style_all=&#8221;dotted&#8221; border_width_top=&#8221;1px&#8221; border_color_top=&#8221;#575756&#8243; border_width_right=&#8221;1px&#8221; border_width_bottom=&#8221;1px&#8221; border_width_left=&#8221;1px&#8221; image_max_width=&#8221;73%&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: center;\"><strong>WarmWhite<br \/><\/strong>(WW + AR)<\/p>\n<p style=\"text-align: center;\">[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_6&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;CLUSTER B2 FC&#8221; url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjE1NTAyIn19@&#8221; image=&#8221;https:\/\/roxxlight.com\/wp-content\/uploads\/2022\/03\/Cluster-B2FC-800&#215;800-2.jpg&#8221; image_icon_width=&#8221;70%&#8221; content_last_edited=&#8221;off|desktop&#8221; _builder_version=&#8221;4.17.6&#8243; _dynamic_attributes=&#8221;url,link_option_url&#8221; header_level=&#8221;h3&#8243; header_font=&#8221;|300|||||||&#8221; header_text_color=&#8221;#DBA000&#8243; header_font_size=&#8221;14px&#8221; body_line_height=&#8221;1.2em&#8221; text_orientation=&#8221;center&#8221; link_option_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjE1NTAyIn19@&#8221; border_color_all=&#8221;#575756&#8243; border_style_all=&#8221;dotted&#8221; border_width_top=&#8221;1px&#8221; border_color_top=&#8221;#575756&#8243; border_width_right=&#8221;1px&#8221; border_width_bottom=&#8221;1px&#8221; border_width_left=&#8221;1px&#8221; image_max_width=&#8221;73%&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: center;\"><strong>Colore completo<br \/><\/strong>(RGBA + WW)<strong><br \/><\/strong><\/p>\n<p style=\"text-align: center;\">[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_6&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;CLUSTER B4 W&#8221; url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjE1NTIxIn19@&#8221; image=&#8221;https:\/\/roxxlight.com\/wp-content\/uploads\/2022\/03\/Cluster-B4W-800&#215;800-1.jpg&#8221; image_icon_width=&#8221;70%&#8221; content_last_edited=&#8221;off|desktop&#8221; _builder_version=&#8221;4.17.6&#8243; _dynamic_attributes=&#8221;url,link_option_url&#8221; header_level=&#8221;h3&#8243; header_font=&#8221;|300|||||||&#8221; header_text_color=&#8221;#DBA000&#8243; header_font_size=&#8221;14px&#8221; body_line_height=&#8221;1.2em&#8221; text_orientation=&#8221;center&#8221; link_option_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjE1NTIxIn19@&#8221; border_color_all=&#8221;#575756&#8243; border_style_all=&#8221;dotted&#8221; border_width_top=&#8221;1px&#8221; border_color_top=&#8221;#575756&#8243; border_width_right=&#8221;1px&#8221; border_width_bottom=&#8221;1px&#8221; border_width_left=&#8221;1px&#8221; image_max_width=&#8221;73%&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: center;\"><strong>Bianco caldo<br \/><\/strong>(WW + AR)<strong><\/strong><strong><\/strong><\/p>\n<p style=\"text-align: center;\">[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_6&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;CLUSTER B4 FC&#8221; url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjE1NTU1In19@&#8221; image=&#8221;https:\/\/roxxlight.com\/wp-content\/uploads\/2022\/03\/Cluster-B4FC-800&#215;800-1.jpg&#8221; image_icon_width=&#8221;70%&#8221; content_last_edited=&#8221;off|desktop&#8221; _builder_version=&#8221;4.17.6&#8243; _dynamic_attributes=&#8221;url,link_option_url&#8221; header_level=&#8221;h3&#8243; header_font=&#8221;|300|||||||&#8221; header_text_color=&#8221;#DBA000&#8243; header_font_size=&#8221;14px&#8221; body_line_height=&#8221;1.2em&#8221; text_orientation=&#8221;center&#8221; link_option_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjE1NTU1In19@&#8221; border_color_all=&#8221;#575756&#8243; border_style_all=&#8221;dotted&#8221; border_width_top=&#8221;1px&#8221; border_color_top=&#8221;#575756&#8243; border_width_right=&#8221;1px&#8221; border_width_bottom=&#8221;1px&#8221; border_width_left=&#8221;1px&#8221; image_max_width=&#8221;73%&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: center;\"><strong>Colore completo<br \/><\/strong>(RGBA + WW)<\/p>\n<p style=\"text-align: center;\">[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_6&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;CLUSTER S2&#8243; url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjE4OTE4In19@&#8221; image=&#8221;https:\/\/roxxlight.com\/wp-content\/uploads\/2022\/03\/Cluster-s2-800&#215;800-1.png&#8221; image_icon_width=&#8221;70%&#8221; content_last_edited=&#8221;off|desktop&#8221; _builder_version=&#8221;4.25.1&#8243; _dynamic_attributes=&#8221;url,link_option_url&#8221; header_level=&#8221;h3&#8243; header_font=&#8221;|300|||||||&#8221; header_text_color=&#8221;#DBA000&#8243; header_font_size=&#8221;14px&#8221; body_line_height=&#8221;1.2em&#8221; text_orientation=&#8221;center&#8221; link_option_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjE4OTE4In19@&#8221; border_color_all=&#8221;#575756&#8243; border_style_all=&#8221;dotted&#8221; border_width_top=&#8221;1px&#8221; border_color_top=&#8221;#575756&#8243; border_width_right=&#8221;1px&#8221; border_width_bottom=&#8221;1px&#8221; border_width_left=&#8221;1px&#8221; image_max_width=&#8221;73%&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: center;\"><strong>Pixel-mappabile <\/strong><br \/><strong>Ibrido strobo\/lavaggio<\/strong><\/p>\n<p style=\"text-align: center;\">[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_6&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row disabled_on=&#8221;off|on|on&#8221; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][dica_divi_carousel multislide=&#8221;on&#8221; centermode=&#8221;on&#8221; dot_nav=&#8221;on&#8221; equal_height=&#8221;on&#8221; advanced_effect=&#8221;1&#8243; dots_color=&#8221;#DBA000&#8243; dots_active_color=&#8221;#575756&#8243; title_background=&#8221;RGBA(255,255,255,0)&#8221; image_sizing=&#8221;80%&#8221; arrow_alignment=&#8221;center&#8221; arrow_font_size=&#8221;35px&#8221; arrow_position_tablet=&#8221;&#8221; arrow_position_phone=&#8221;middle-outside&#8221; arrow_position_last_edited=&#8221;on|phone&#8221; disabled_on=&#8221;off|on|on&#8221; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; title_font=&#8221;|300|||||||&#8221; title_text_align=&#8221;left&#8221; title_text_color=&#8221;#DBA000&#8243; subtitle_font=&#8221;||||||||&#8221; subtitle_text_align=&#8221;center&#8221; subtitle_text_color=&#8221;#575756&#8243; title_text_align_tablet=&#8221;&#8221; title_text_align_phone=&#8221;center&#8221; title_text_align_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][dica_divi_carouselitem title=&#8221;CLUSTER S2&#8243; sub_title=&#8221;Strobo\/lavaggio ibrido mappabile con i pixel&#8221; button_url_new_window=&#8221;1&#8243; image=&#8221;https:\/\/roxxlight.com\/wp-content\/uploads\/2022\/03\/Cluster-s2-800&#215;800-1.png&#8221; _builder_version=&#8221;4.17.6&#8243; _dynamic_attributes=&#8221;link_option_url&#8221; _module_preset=&#8221;default&#8221; header_text_align=&#8221;center&#8221; link_option_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjE4OTE4In19@&#8221; global_colors_info=&#8221;{}&#8221;][\/dica_divi_carouselitem][dica_divi_carouselitem title=&#8221;CLUSTER B4 W&#8221; sub_title=&#8221;(LED bianco caldo + ambra + rosso)&#8221; button_url_new_window=&#8221;1&#8243; image=&#8221;https:\/\/roxxlight.com\/wp-content\/uploads\/2022\/03\/Cluster-B4W-800&#215;800-1.jpg&#8221; _builder_version=&#8221;4.17.6&#8243; _dynamic_attributes=&#8221;link_option_url&#8221; _module_preset=&#8221;default&#8221; header_text_align=&#8221;center&#8221; link_option_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjE1NTIxIn19@&#8221; global_colors_info=&#8221;{}&#8221;][\/dica_divi_carouselitem][dica_divi_carouselitem title=&#8221;CLUSTER B2 W&#8221; sub_title=&#8221;Bianco caldo (LED bianco caldo + ambra + rosso)&#8221; button_url_new_window=&#8221;1&#8243; image=&#8221;https:\/\/roxxlight.com\/wp-content\/uploads\/2022\/03\/Cluster-B2W-800&#215;800-1.jpg&#8221; _builder_version=&#8221;4.17.6&#8243; _dynamic_attributes=&#8221;link_option_url&#8221; _module_preset=&#8221;default&#8221; header_text_align=&#8221;center&#8221; subtitle_font=&#8221;||||||||&#8221; subtitle_text_align=&#8221;center&#8221; subtitle_text_color=&#8221;#575756&#8243; link_option_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjE1MzM4In19@&#8221; global_colors_info=&#8221;{}&#8221;][\/dica_divi_carouselitem][dica_divi_carouselitem title=&#8221;CLUSTER B2 FC&#8221; sub_title=&#8221;Colore pieno (RGBA + LED bianco caldo)&#8221; button_url_new_window=&#8221;1&#8243; image=&#8221;https:\/\/roxxlight.com\/wp-content\/uploads\/2022\/03\/Cluster-B2FC-800&#215;800-2.jpg&#8221; _builder_version=&#8221;4.17.6&#8243; _dynamic_attributes=&#8221;link_option_url&#8221; _module_preset=&#8221;default&#8221; header_text_align=&#8221;center&#8221; subtitle_font=&#8221;||||||||&#8221; subtitle_text_align=&#8221;center&#8221; subtitle_text_color=&#8221;#575756&#8243; link_option_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjE1NTAyIn19@&#8221; global_colors_info=&#8221;{}&#8221;][\/dica_divi_carouselitem][dica_divi_carouselitem title=&#8221;CLUSTER B4 FC&#8221; sub_title=&#8221;Colore pieno (RGBA + LED bianco caldo)&#8221; button_url_new_window=&#8221;1&#8243; image=&#8221;https:\/\/roxxlight.com\/wp-content\/uploads\/2022\/03\/Cluster-B4FC-800&#215;800-1.jpg&#8221; _builder_version=&#8221;4.17.6&#8243; _dynamic_attributes=&#8221;link_option_url&#8221; _module_preset=&#8221;default&#8221; header_text_align=&#8221;center&#8221; link_option_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjE1NTU1In19@&#8221; global_colors_info=&#8221;{}&#8221;][\/dica_divi_carouselitem][\/dica_divi_carousel][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_module=&#8221;22425&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;-50px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_social_media_follow disabled_on=&#8221;off|off|off&#8221; _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; text_orientation=&#8221;center&#8221; custom_margin_tablet=&#8221;&#8221; custom_margin_phone=&#8221;-25px||||false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_social_media_follow_network social_network=&#8221;facebook&#8221; url=&#8221;https:\/\/www.facebook.com\/roxxlight&#8221; _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#3b5998&#8243; global_colors_info=&#8221;{}&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]facebook[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=&#8221;instagram&#8221; url=&#8221;https:\/\/www.instagram.com\/roxx.light\/&#8221; _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#ea2c59&#8243; global_colors_info=&#8221;{}&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]instagram[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=&#8221;linkedin&#8221; url=&#8221;https:\/\/www.linkedin.com\/company\/roxx-gmbh\/&#8221; _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#007bb6&#8243; global_colors_info=&#8221;{}&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]linkedin[\/et_pb_social_media_follow_network][\/et_pb_social_media_follow][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CLUSTER Line Array | Backbone 2+2Il backbone 2+2 collega due 2-Lite, sia che si utilizzi B2+B2, S2+S2 o uno di questi. Ogni backbone del CLUSTER Line Array Set offre un&#8217;ampia gamma di regolazioni angolari, tra cui angoli positivi da 0\u00b0 a 20\u00b0 e angoli negativi da -2,5\u00b0 a -20\u00b0. Caratteristiche principali elemento centrale di supporto [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-31246","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cluster-Linea Array-Backbone-2-2 - Roxxlight<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/roxxlight.com\/cluster-line-array-backbone-2-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cluster-Linea Array-Backbone-2-2 - Roxxlight\" \/>\n<meta property=\"og:description\" content=\"CLUSTER Line Array | Backbone 2+2Il backbone 2+2 collega due 2-Lite, sia che si utilizzi B2+B2, S2+S2 o uno di questi. Ogni backbone del CLUSTER Line Array Set offre un&#039;ampia gamma di regolazioni angolari, tra cui angoli positivi da 0\u00b0 a 20\u00b0 e angoli negativi da -2,5\u00b0 a -20\u00b0. Caratteristiche principali elemento centrale di supporto [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/roxxlight.com\/cluster-line-array-backbone-2-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Roxxlight\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/roxxlight\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-18T09:10:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/roxxlight.com\/wp-content\/uploads\/2021\/02\/Icons-download.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"18 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/roxxlight.com\\\/cluster-line-array-backbone-2-2\\\/\",\"url\":\"https:\\\/\\\/roxxlight.com\\\/cluster-line-array-backbone-2-2\\\/\",\"name\":\"Cluster-Linea Array-Backbone-2-2 - Roxxlight\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/roxxlight.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/roxxlight.com\\\/cluster-line-array-backbone-2-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/roxxlight.com\\\/cluster-line-array-backbone-2-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/roxxlight.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Icons-download.png\",\"datePublished\":\"2024-09-18T07:56:44+00:00\",\"dateModified\":\"2024-09-18T09:10:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/roxxlight.com\\\/cluster-line-array-backbone-2-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/roxxlight.com\\\/cluster-line-array-backbone-2-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/roxxlight.com\\\/cluster-line-array-backbone-2-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/roxxlight.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Icons-download.png\",\"contentUrl\":\"https:\\\/\\\/roxxlight.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Icons-download.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/roxxlight.com\\\/cluster-line-array-backbone-2-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/roxxlight.com\\\/it\\\/casa__trashed\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cluster-Linea Array-Backbone-2-2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/roxxlight.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/roxxlight.com\\\/de\\\/\",\"name\":\"Roxxlight\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/roxxlight.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/roxxlight.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/roxxlight.com\\\/de\\\/#organization\",\"name\":\"Roxxlight\",\"url\":\"https:\\\/\\\/roxxlight.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/roxxlight.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/roxxlight.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-ROXX_Newsletter-black.png\",\"contentUrl\":\"https:\\\/\\\/roxxlight.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-ROXX_Newsletter-black.png\",\"width\":600,\"height\":114,\"caption\":\"Roxxlight\"},\"image\":{\"@id\":\"https:\\\/\\\/roxxlight.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/roxxlight\",\"https:\\\/\\\/www.instagram.com\\\/roxx.light\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cluster-Linea Array-Backbone-2-2 - Roxxlight","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/roxxlight.com\/cluster-line-array-backbone-2-2\/","og_locale":"it_IT","og_type":"article","og_title":"Cluster-Linea Array-Backbone-2-2 - Roxxlight","og_description":"CLUSTER Line Array | Backbone 2+2Il backbone 2+2 collega due 2-Lite, sia che si utilizzi B2+B2, S2+S2 o uno di questi. Ogni backbone del CLUSTER Line Array Set offre un'ampia gamma di regolazioni angolari, tra cui angoli positivi da 0\u00b0 a 20\u00b0 e angoli negativi da -2,5\u00b0 a -20\u00b0. Caratteristiche principali elemento centrale di supporto [&hellip;]","og_url":"https:\/\/roxxlight.com\/cluster-line-array-backbone-2-2\/","og_site_name":"Roxxlight","article_publisher":"https:\/\/www.facebook.com\/roxxlight","article_modified_time":"2024-09-18T09:10:38+00:00","og_image":[{"url":"https:\/\/roxxlight.com\/wp-content\/uploads\/2021\/02\/Icons-download.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"18 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/roxxlight.com\/cluster-line-array-backbone-2-2\/","url":"https:\/\/roxxlight.com\/cluster-line-array-backbone-2-2\/","name":"Cluster-Linea Array-Backbone-2-2 - Roxxlight","isPartOf":{"@id":"https:\/\/roxxlight.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/roxxlight.com\/cluster-line-array-backbone-2-2\/#primaryimage"},"image":{"@id":"https:\/\/roxxlight.com\/cluster-line-array-backbone-2-2\/#primaryimage"},"thumbnailUrl":"https:\/\/roxxlight.com\/wp-content\/uploads\/2021\/02\/Icons-download.png","datePublished":"2024-09-18T07:56:44+00:00","dateModified":"2024-09-18T09:10:38+00:00","breadcrumb":{"@id":"https:\/\/roxxlight.com\/cluster-line-array-backbone-2-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/roxxlight.com\/cluster-line-array-backbone-2-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/roxxlight.com\/cluster-line-array-backbone-2-2\/#primaryimage","url":"https:\/\/roxxlight.com\/wp-content\/uploads\/2021\/02\/Icons-download.png","contentUrl":"https:\/\/roxxlight.com\/wp-content\/uploads\/2021\/02\/Icons-download.png"},{"@type":"BreadcrumbList","@id":"https:\/\/roxxlight.com\/cluster-line-array-backbone-2-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/roxxlight.com\/it\/casa__trashed\/"},{"@type":"ListItem","position":2,"name":"Cluster-Linea Array-Backbone-2-2"}]},{"@type":"WebSite","@id":"https:\/\/roxxlight.com\/de\/#website","url":"https:\/\/roxxlight.com\/de\/","name":"Roxxlight","description":"","publisher":{"@id":"https:\/\/roxxlight.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/roxxlight.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/roxxlight.com\/de\/#organization","name":"Roxxlight","url":"https:\/\/roxxlight.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/roxxlight.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/roxxlight.com\/wp-content\/uploads\/2024\/04\/Logo-ROXX_Newsletter-black.png","contentUrl":"https:\/\/roxxlight.com\/wp-content\/uploads\/2024\/04\/Logo-ROXX_Newsletter-black.png","width":600,"height":114,"caption":"Roxxlight"},"image":{"@id":"https:\/\/roxxlight.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/roxxlight","https:\/\/www.instagram.com\/roxx.light\/"]}]}},"_links":{"self":[{"href":"https:\/\/roxxlight.com\/it\/wp-json\/wp\/v2\/pages\/31246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roxxlight.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/roxxlight.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/roxxlight.com\/it\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/roxxlight.com\/it\/wp-json\/wp\/v2\/comments?post=31246"}],"version-history":[{"count":10,"href":"https:\/\/roxxlight.com\/it\/wp-json\/wp\/v2\/pages\/31246\/revisions"}],"predecessor-version":[{"id":31379,"href":"https:\/\/roxxlight.com\/it\/wp-json\/wp\/v2\/pages\/31246\/revisions\/31379"}],"wp:attachment":[{"href":"https:\/\/roxxlight.com\/it\/wp-json\/wp\/v2\/media?parent=31246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}